{"id":6409,"date":"2020-09-14T11:15:55","date_gmt":"2020-09-14T09:15:55","guid":{"rendered":"http:\/\/neustadtarchitekten.de\/?p=6409"},"modified":"2020-12-16T12:28:18","modified_gmt":"2020-12-16T11:28:18","slug":"bim-certificate","status":"publish","type":"post","link":"https:\/\/neustadtarchitekten.de\/en\/bim-certificate\/","title":{"rendered":"Graphisoft BIM Certificate"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc-row-container container\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  post-formatting\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: left;\"><strong>Wir haben die Expertin im Haus!<\/strong><\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6410 size-medium\" src=\"http:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-300x212.jpg\" alt=\"BIM Certificate\" width=\"300\" height=\"212\" srcset=\"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-300x212.jpg 300w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-768x543.jpg 768w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-1024x724.jpg 1024w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-1612x1140.jpg 1612w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-1116x789.jpg 1116w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-806x570.jpg 806w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-558x395.jpg 558w, https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/GS_BIM_Manager_Certificate_GS001-CABM-202000087_Gudrun_Geest-signed-655x463.jpg 655w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Mit BIM arbeiten wir bereits seit l\u00e4ngerem. Nun haben wir eine weitere Expertise in unserem B\u00fcro.<\/p>\n<p>Unsere Mitarbeiterin Gudrun Geest hat sich erfolgreich zur BIM Managerin ausbilden lassen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir gratulieren!<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc-row-container container\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wir haben die Expertin im Haus!<\/p>","protected":false},"author":1,"featured_media":6411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,1,33],"tags":[],"class_list":["post-6409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-allgemein","category-projekte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Graphisoft BIM Certificate - Neustadtarchitekten<\/title>\n<meta name=\"description\" content=\"Neustadtarchitekten - Graphisoft BIM Certificate -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/neustadtarchitekten.de\/en\/bim-certificate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graphisoft BIM Certificate - Neustadtarchitekten\" \/>\n<meta property=\"og:description\" content=\"Neustadtarchitekten - Graphisoft BIM Certificate -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/neustadtarchitekten.de\/en\/bim-certificate\/\" \/>\n<meta property=\"og:site_name\" content=\"Neustadtarchitekten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Neustadtarchitekten-282231286044257\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T09:15:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-16T11:28:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NsaAdmin01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"NsaAdmin01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/\",\"url\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/\",\"name\":\"Graphisoft BIM Certificate - Neustadtarchitekten\",\"isPartOf\":{\"@id\":\"https:\/\/neustadtarchitekten.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg\",\"datePublished\":\"2020-09-14T09:15:55+00:00\",\"dateModified\":\"2020-12-16T11:28:18+00:00\",\"author\":{\"@id\":\"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/db431c10dfafd3ef3d5cb3bde309357e\"},\"description\":\"Neustadtarchitekten - Graphisoft BIM Certificate -\",\"breadcrumb\":{\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/neustadtarchitekten.de\/bim-certificate\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage\",\"url\":\"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg\",\"contentUrl\":\"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/neustadtarchitekten.de\/bim-certificate\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/neustadtarchitekten.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graphisoft BIM Certificate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/neustadtarchitekten.de\/#website\",\"url\":\"https:\/\/neustadtarchitekten.de\/\",\"name\":\"Neustadtarchitekten\",\"description\":\"Projekte und Aktuelles aus unserem Architekturb\u00fcro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/neustadtarchitekten.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/db431c10dfafd3ef3d5cb3bde309357e\",\"name\":\"NsaAdmin01\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2b3131c5b88e9dd0bf3898cd4353ff7e66d4aa6f68f1deff6d5b6b98326b022?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2b3131c5b88e9dd0bf3898cd4353ff7e66d4aa6f68f1deff6d5b6b98326b022?s=96&d=mm&r=g\",\"caption\":\"NsaAdmin01\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Graphisoft BIM Certificate - Neustadtarchitekten","description":"Neustadtarchitekten - Graphisoft BIM Certificate -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/neustadtarchitekten.de\/en\/bim-certificate\/","og_locale":"en_US","og_type":"article","og_title":"Graphisoft BIM Certificate - Neustadtarchitekten","og_description":"Neustadtarchitekten - Graphisoft BIM Certificate -","og_url":"https:\/\/neustadtarchitekten.de\/en\/bim-certificate\/","og_site_name":"Neustadtarchitekten","article_publisher":"https:\/\/www.facebook.com\/Neustadtarchitekten-282231286044257","article_published_time":"2020-09-14T09:15:55+00:00","article_modified_time":"2020-12-16T11:28:18+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg","type":"image\/jpeg"}],"author":"NsaAdmin01","twitter_card":"summary_large_image","twitter_misc":{"Written by":"NsaAdmin01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/","url":"https:\/\/neustadtarchitekten.de\/bim-certificate\/","name":"Graphisoft BIM Certificate - Neustadtarchitekten","isPartOf":{"@id":"https:\/\/neustadtarchitekten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage"},"image":{"@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage"},"thumbnailUrl":"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg","datePublished":"2020-09-14T09:15:55+00:00","dateModified":"2020-12-16T11:28:18+00:00","author":{"@id":"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/db431c10dfafd3ef3d5cb3bde309357e"},"description":"Neustadtarchitekten - Graphisoft BIM Certificate -","breadcrumb":{"@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/neustadtarchitekten.de\/bim-certificate\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/#primaryimage","url":"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg","contentUrl":"https:\/\/neustadtarchitekten.de\/wp-content\/uploads\/2020\/10\/Template-Aktuelles-Bild-Website.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/neustadtarchitekten.de\/bim-certificate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/neustadtarchitekten.de\/"},{"@type":"ListItem","position":2,"name":"Graphisoft BIM Certificate"}]},{"@type":"WebSite","@id":"https:\/\/neustadtarchitekten.de\/#website","url":"https:\/\/neustadtarchitekten.de\/","name":"Neustadtarchitekten","description":"Projekte und Aktuelles aus unserem Architekturb\u00fcro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/neustadtarchitekten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/db431c10dfafd3ef3d5cb3bde309357e","name":"NsaAdmin01","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/neustadtarchitekten.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d2b3131c5b88e9dd0bf3898cd4353ff7e66d4aa6f68f1deff6d5b6b98326b022?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2b3131c5b88e9dd0bf3898cd4353ff7e66d4aa6f68f1deff6d5b6b98326b022?s=96&d=mm&r=g","caption":"NsaAdmin01"}}]}},"_links":{"self":[{"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/6409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/comments?post=6409"}],"version-history":[{"count":4,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/6409\/revisions"}],"predecessor-version":[{"id":6467,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/posts\/6409\/revisions\/6467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/media\/6411"}],"wp:attachment":[{"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/media?parent=6409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/categories?post=6409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neustadtarchitekten.de\/en\/wp-json\/wp\/v2\/tags?post=6409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}